{"id":89146,"date":"2016-08-02T13:33:19","date_gmt":"2016-08-02T13:33:19","guid":{"rendered":"http:\/\/www.upla.cl\/noticias\/?p=89146"},"modified":"2016-08-02T13:33:19","modified_gmt":"2016-08-02T13:33:19","slug":"frente-a-una-reforma-a-la-educacion-superior","status":"publish","type":"post","link":"https:\/\/www.upla.cl\/facultad\/ingenieria\/2016\/08\/02\/frente-a-una-reforma-a-la-educacion-superior\/","title":{"rendered":"Frente a una reforma a la educaci\u00f3n superior"},"content":{"rendered":"<h5><strong>A la comunidad universitaria:<\/strong><\/h5>\n<p>Estamos frente a una reforma a la educaci\u00f3n superior que no satisface nuestras expectativas en variados aspectos. Si bien es posible reconocer algunos avances en los \u00e1mbitos de la institucionalidad y aseguramiento de la calidad, quienes suscribimos este documento hemos hecho un an\u00e1lisis acerca de los temas que deber\u00edan ser modificados a trav\u00e9s de indicaciones.<\/p>\n<p>Entre los aspectos m\u00e1s cr\u00edticos que deber\u00edan ser modificados, est\u00e1 el modelo de educaci\u00f3n superior que se pretende perpetuar. No nos parece que el mercado de la educaci\u00f3n superior se mantenga bajo ning\u00fan aspecto, para lo cual es necesario desterrar el Cr\u00e9dito con Aval del Estado (CAE) que termina bancarizando el sistema de financiamiento de las universidades, hipotecando el futuro de los estudiantes.<\/p>\n<p>Si bien el proyecto declara un apoyo al fortalecimiento de las universidades estatales, en la pr\u00e1ctica dicha promesa no se materializa en ninguna parte de esta iniciativa. La desaparici\u00f3n progresiva del aporte fiscal directo (AFD) es una medida inadecuada porque son los \u00fanicos recursos permanentes de nuestras universidades, aunque para la Universidad de Playa Ancha son muy bajos comparados con el resto del sistema.<\/p>\n<p>La transformaci\u00f3n de estos aportes en recursos que dependan de las leyes anuales de presupuesto los hace inestables y dependientes de la voluntad pol\u00edtica de los gobiernos de turno. La propuesta de ley establece clasificaciones de universidades que se basan en su respectiva adscripci\u00f3n a la gratuidad. Objetamos que las universidades que no adscriban a la gratuidad reciban becas, CAE y tampoco tengan l\u00edmites para fijar los cupos anuales de admisi\u00f3n y los montos de sus aranceles, al contrario de lo que ocurrir\u00e1 con nuestras universidades que tendr\u00e1n cupos y aranceles regulados. Esto es, un conjunto de universidades que seguir\u00e1 actuando en el mercado libremente, con apoyo estatal y otras que lo hacen con restricciones y regulaciones.<\/p>\n<p>No avalamos que las universidades del Estado tengan que financiarse principalmente a trav\u00e9s del n\u00famero de alumnos que se matricule porque, aunque lo pague el Estado, es en definitiva un subsidio a la demanda y no a la oferta como hemos proclamado y definido. Lo anterior no atiende las responsabilidades p\u00fablicas de financiar universidades complejas que desarrollan investigaci\u00f3n, postgrado y vinculaci\u00f3n con el medio y que mantienen carreras con gran impacto social y con menor matr\u00edcula como son algunas pedagog\u00edas, entre otros.<\/p>\n<p>Tampoco estamos de acuerdo con los l\u00edmites a la autonom\u00eda universitaria que se manifiesta en varios ac\u00e1pites del proyecto de ley, entre los cuales est\u00e1n las limitaciones para la apertura de nuevas carreras, la intromisi\u00f3n excesiva del Estado en la gobernanza de las universidades estatales, la duplicidad de controles entre la Contralor\u00eda General de la Rep\u00fablica y la nueva Superintendencia de Educaci\u00f3n Superior. Rechazamos la omisi\u00f3n que el proyecto de ley hace de las universidades regionales, en especial porque desconoce su labor y las dificultades que implica desenvolverse en condiciones adversas, en lugares aislados, zonas extremas o carentes de poblaci\u00f3n suficiente.<\/p>\n<p>Estas son algunas de nuestras reflexiones iniciales. Para completar este proceso, invitamos a nuestra comunidad a participar en la discusi\u00f3n que haremos en el \u201cIII Seminario sobre la Reforma a la Educaci\u00f3n Superior\u201d, que ha organizado nuestra comunidad universitaria para este mes de agosto, con el prop\u00f3sito de adoptar una posici\u00f3n com\u00fan entre todos los integrantes de la comunidad para elaborar y llevar una propuesta completa sobre esta importante reforma a las instancias legislativas correspondientes. En este esp\u00edritu llamamos a los estamentos y en especial a los estudiantes a sumarse a las distintas instancias de discusi\u00f3n de esta importante reforma.<\/p>\n<p>Finalmente y de manera tambi\u00e9n especial, no podemos de dejar de manifestar nuestra preocupaci\u00f3n por el tiempo de paralizaci\u00f3n estudiantil. La Universidad reitera su compromiso con la calidad y es por ello que debe realizar las dieciocho semanas lectivas en cada semestre. Por lo anterior, hacemos un llamado a normalizar el primer semestre a la brevedad, considerando que debemos velar por la excelencia acad\u00e9mica, la mantenci\u00f3n de los beneficios estudiantiles en los tiempos fijados por el Mineduc, la calidad de vida de nuestros estudiantes, acad\u00e9micos y funcionarios, a quienes les asiste el derecho a tener sus vacaciones de verano en los tiempos programados.<\/p>\n<p>Patricio Sanhueza Vivanco<br \/>\nRector<\/p>\n<p>Juan Saavedra \u00c1vila<br \/>\nDecano Facultad de Humanidades<\/p>\n<p>Luis Alberto D\u00edaz Arancibia<br \/>\nDecano Facultad de Cs. de la Educaci\u00f3n<\/p>\n<p>Felip Gasc\u00f3n i Mart\u00edn<br \/>\nDecano Facultad de Cs. Sociales<\/p>\n<p>Alberto Madrid Letelier<br \/>\nDecano Facultad de Arte<\/p>\n<p>Jos\u00e9 Rubio Valenzuela<br \/>\nDecano Facultad de Cs. Naturales y Exactas<\/p>\n<p>Mirta Crovetto Mattassi<br \/>\nDecana Facultad de Cs. de la Salud<\/p>\n<p>Ver\u00f3nica Meza Ram\u00edrez<br \/>\nDecana Facultad de Ingenier\u00eda<\/p>\n<p>C\u00e9sar Oliva Aravena<br \/>\nDecano Facultad de Cs. de la Act. F\u00edsica y del Deporte<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El rector Patricio Sanhueza Vivanco junto a los ocho decanos de las facultades del campus Valpara\u00edso presentan su postura sobre el proyecto de ley que tramita el gobierno. <\/p>\n","protected":false},"author":1,"featured_media":81076,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-89146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"_links":{"self":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts\/89146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/comments?post=89146"}],"version-history":[{"count":0,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts\/89146\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/media?parent=89146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/categories?post=89146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/tags?post=89146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}