{"id":88481,"date":"2016-07-13T08:30:08","date_gmt":"2016-07-13T08:30:08","guid":{"rendered":"http:\/\/www.upla.cl\/noticias\/?p=88481"},"modified":"2016-07-13T08:30:08","modified_gmt":"2016-07-13T08:30:08","slug":"estudiantes-y-academicos-de-la-facultad-de-ingenieria-en-franco-dialogo","status":"publish","type":"post","link":"https:\/\/www.upla.cl\/facultad\/ingenieria\/2016\/07\/13\/estudiantes-y-academicos-de-la-facultad-de-ingenieria-en-franco-dialogo\/","title":{"rendered":"Estudiantes y acad\u00e9micos de la Facultad de Ingenier\u00eda en franco di\u00e1logo"},"content":{"rendered":"<p><a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2016\/07\/Vero\u0301nica-Meza-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-88484\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2016\/07\/Vero\u0301nica-Meza-1-300x169.jpg\" alt=\"Vero\u0301nica Meza 1\" width=\"300\" height=\"169\" \/><\/a><br \/>\nLa innovaci\u00f3n curricular de Ingenier\u00eda Civil Industrial, Ingenier\u00eda Civil Ambiental e Ingenier\u00eda Ambiental; adem\u00e1s del trabajo con miras a la acreditaci\u00f3n y la planificaci\u00f3n estrat\u00e9gica, son los pr\u00f3ximos desaf\u00edos que enfrentar\u00e1 la Facultad de Ingenier\u00eda, seg\u00fan lo plante\u00f3 la Decana (s) <strong>Ver\u00f3nica Meza Ram\u00edrez,<\/strong> en la asamblea biestamental que realiz\u00f3 recientemente dicha unidad acad\u00e9mica.<\/p>\n<p>En este primer encuentro participaron estudiantes y acad\u00e9micos de todas las carreras (Ingenier\u00eda Ambiental, Ingenier\u00eda Civil Ambiental, Ingenier\u00eda Civil Industrial, Ingenier\u00eda en Inform\u00e1tica e Ingenier\u00eda en Estad\u00edstica), quienes valoraron esta instancia de di\u00e1logo y reflexi\u00f3n.<\/p>\n<p>En la cita, la decana (s) present\u00f3 los principales hitos del trabajo conjunto de los acad\u00e9micos, entre los que destac\u00f3 los siguientes:<\/p>\n<p>-Resultados de aprobaci\u00f3n de \u00c1lgebra y C\u00e1lculo diferencial, en el marco de la implementaci\u00f3n del proyecto FACING en 2015 y 2016.<\/p>\n<p>-Competencias Nucleares de la Facultad en 2015, gestionadas por el exdecano <strong>Manuel Contreras.<\/strong><\/p>\n<p>-Registro de investigaciones, con producci\u00f3n de proyectos postulados, adjudicados y publicaciones.<\/p>\n<p>-Trabajo sistem\u00e1tico relacionado con el sello, orientado hacia la comunidad estudiantil, m\u00e1s el desarrollo de redes activas con universidades chilenas, latinoamericanas y europeas.<\/p>\n<p>-Acad\u00e9micos de la facultad con estudios o cursando postgrado.<\/p>\n<p>-Estado de la planificaci\u00f3n estrat\u00e9gica. Se destaca la primera misi\u00f3n de la facultad y los trabajos de los acad\u00e9micos durante el plazo en que <strong>Daniel Valdivia<\/strong> asumi\u00f3 la decanatura.<\/p>\n<p>-Trabajo de los estudiantes: tesis pa\u00eds (con problemas cr\u00edticos), Proyecto Idea, o los DGI adjudicados por estudiantes de la Facultad de Ingenier\u00eda que en este a\u00f1o representan un 26,6%.<\/p>\n<h5><strong>Alta valoraci\u00f3n<\/strong><\/h5>\n<p><a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2016\/07\/Vero\u0301nica-Meza-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-88487\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2016\/07\/Vero\u0301nica-Meza-2-300x169.jpg\" alt=\"Vero\u0301nica Meza 2\" width=\"300\" height=\"169\" \/><\/a>Dentro de las inquietudes y peticiones planteadas por los estudiantes destacaron: La falta de ayudant\u00edas y la remuneraci\u00f3n de las mismas y demora de la innovaci\u00f3n curricular, entre otros temas.<\/p>\n<p>Para la <strong>directora del Departamento de Medio Ambiente Dra. (c)<\/strong> <strong>Eva Soto Acevedo,<\/strong> este encuentro fue una excelente oportunidad para compartir y dialogar entre los dos estamentos (acad\u00e9micos y estudiantil), adem\u00e1s de directivos de la Facultad de Ingenier\u00eda, en un clima de respeto de consenso y disenso.<\/p>\n<p>\u201cFue muy positivo analizar la contingencia de nuestra unidad, como por ejemplo, la falta de ayudant\u00edas y que se les remunere -principal problema se\u00f1alado por los alumnos-. Es una demanda reiterada en cada uno de los petitorios desde 2013, pero a\u00fan no se llega a soluci\u00f3n por parte de la autoridad institucional\u201d, dijo <strong>Eva Soto.<\/strong><\/p>\n<p>Seg\u00fan el <strong>director del Departamento de Industria y Econom\u00eda, Mg. Luis Espinoza Brito<\/strong>, la asamblea fue una instancia de comunicaci\u00f3n entre estudiantes y profesores, que permiti\u00f3 poner en com\u00fan los temas que requieren mayor atenci\u00f3n.<\/p>\n<p>Una opini\u00f3n similar comparti\u00f3 el Dr. (c)\u00a0<strong>Miguel Guevara Albornoz<\/strong>, quien sostuvo que este tipo de jornadas permite avanzar en el crecimiento y desarrollo de la facultad, sobre la base de la comunicaci\u00f3n transversal y constructiva.<\/p>\n<p>A modo de conclusi\u00f3n, se defini\u00f3 realizar una solicitud a las autoridades de la universidad respecto a contar con ayudantes remunerados, y se form\u00f3 una comisi\u00f3n de docentes y estudiantes para recopilar informaci\u00f3n sobre peticiones de a\u00f1os anteriores, con la finalidad de dar seguimiento en la b\u00fasqueda de soluciones.<\/p>\n<p>La pr\u00f3xima asamblea ser\u00e1 triestamental -a petici\u00f3n de los estudiantes- y se realizar\u00e1 el 27 de agosto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00f3xima asamblea se realizar\u00e1 el 27 de agosto  y ser\u00e1 de car\u00e1cter triestamental.<\/p>\n","protected":false},"author":1,"featured_media":88487,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-88481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"_links":{"self":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts\/88481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/comments?post=88481"}],"version-history":[{"count":0,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts\/88481\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/media?parent=88481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/categories?post=88481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/tags?post=88481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}