{"id":79315,"date":"2015-11-04T15:32:20","date_gmt":"2015-11-04T15:32:20","guid":{"rendered":"http:\/\/www.upla.cl\/noticias\/?p=79315"},"modified":"2015-11-04T15:32:20","modified_gmt":"2015-11-04T15:32:20","slug":"experto-espanol-aborda-procesos-para-el-tratamiento-de-aguas","status":"publish","type":"post","link":"https:\/\/www.upla.cl\/facultad\/ingenieria\/2015\/11\/04\/experto-espanol-aborda-procesos-para-el-tratamiento-de-aguas\/","title":{"rendered":"Experto espa\u00f1ol aborda procesos para el tratamiento de aguas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-79322\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2015\/11\/M\u00e9ndez-Pampin-300x200.jpg\" alt=\"M\u00e9ndez Pampin\" width=\"300\" height=\"200\" \/>Con la clase magistral \u201cOptimizaci\u00f3n ambiental de una instalaci\u00f3n de acuicultura en circuito abierto mediante un sistema de cultivo multitr\u00f3fico integrado\u201d, el <strong>Dr. Ram\u00f3n M\u00e9ndez Pamp\u00edn<\/strong> inici\u00f3 oficialmente una serie de actividades acad\u00e9micas que desarrollar\u00e1 durante los pr\u00f3ximos meses en nuestra casa de estudios, adem\u00e1s de inaugurar el segundo semestre de la Facultad de Ingenier\u00eda de la universidad.<\/p>\n<p>El <strong>Dr. M\u00e9ndez<\/strong> es acad\u00e9mico de pre y post grado en el Departamento de Ingenier\u00eda Qu\u00edmica \u00a0en la <strong>Universidad Santiago de Compostela, Espa\u00f1a,<\/strong> donde ha desarrollado una amplia trayectoria en investigaci\u00f3n en el tratamiento de agua de m\u00e1s de 25 a\u00f1os, incluyendo publicaciones ISI y un \u00edndice H (n\u00famero de citaciones) de 31.<\/p>\n<p>Su estada en nuestra instituci\u00f3n obedece a una invitaci\u00f3n que formul\u00f3 la profesora <strong>Marisol Belmonte Soto, directora del proyecto MEC-Conicyt<\/strong> (pasant\u00edas cortas de cient\u00edficos de excelencia del extranjeros a universidades chilenas) de la Facultad de Ingenier\u00eda.<\/p>\n<h4><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-79319\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2015\/11\/Eva-Soto-y-experto-300x200.jpg\" alt=\"Eva Soto y experto\" width=\"300\" height=\"200\" \/>OBJETIVO<\/h4>\n<p>El objetivo de su visita es abordar aspectos docentes entre ambas universidades, vinculados a la labor investigativa, a trav\u00e9s de lo cual se busca suscribir convenios marco para intercambio de profesores y estudiantes.<\/p>\n<p>\u201cEl perfil de la <strong>Universidad de Playa Ancha<\/strong> es muy interesante, por lo tanto, va a ser muy positivo poder establecer lazos m\u00e1s formales entre ambas universidades. Adem\u00e1s, el trabajo puntual que ha desarrollado la profesora <strong>Marisol Belmonte<\/strong> all\u00e1 en <strong>Espa\u00f1a<\/strong> ha abierto las puertas al trabajo colaborativo, lo que es muy positivo\u201d, dijo el <strong>Dr. M\u00e9ndez.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-79320\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2015\/11\/Eva-Soto-y-experto-2-300x200.jpg\" alt=\"Eva Soto y experto 2\" width=\"300\" height=\"200\" \/>En relaci\u00f3n a la l\u00ednea de investigaci\u00f3n que se podr\u00eda desarrollar en forma conjunta, dice relaci\u00f3n con el tratamiento de aguas, como la eliminaci\u00f3n de nitr\u00f3geno (y otros elementos) a trav\u00e9s diversos procesos avanzados, o desarrollar en la creaci\u00f3n de plantas depuradoras que puedan producir energ\u00eda y rentabilidad.<\/p>\n<p>\u201cEsa es la filosof\u00eda: transformar el concepto de residuo en algo que nos pueda dar un valor a\u00f1adido. Afortunadamente, esa es la l\u00ednea es una tendencia que se desarrolla a nivel mundial, por lo que tambi\u00e9n invitamos a educar al respecto\u201d, concluy\u00f3 el experto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dr. Ram\u00f3n M\u00e9ndez Pamp\u00edn dict\u00f3 conferencia magistral, con la cual se inaugur\u00f3 el segundo semestre de la Facultad de Ingenier\u00eda de la universidad.<\/p>\n","protected":false},"author":1,"featured_media":79319,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-79315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"_links":{"self":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts\/79315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/comments?post=79315"}],"version-history":[{"count":0,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts\/79315\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/media?parent=79315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/categories?post=79315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/tags?post=79315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}