{"id":76981,"date":"2015-09-22T12:26:39","date_gmt":"2015-09-22T12:26:39","guid":{"rendered":"http:\/\/www.upla.cl\/noticias\/?p=76981"},"modified":"2015-09-22T12:26:39","modified_gmt":"2015-09-22T12:26:39","slug":"instructivo-de-matricula-segundo-semestre-2015","status":"publish","type":"post","link":"https:\/\/www.upla.cl\/facultad\/ingenieria\/2015\/09\/22\/instructivo-de-matricula-segundo-semestre-2015\/","title":{"rendered":"Instructivo de matr\u00edcula segundo semestre 2015"},"content":{"rendered":"<p>Entre el 23 al 25 de septiembre se realizar\u00e1 el <strong>proceso de matr\u00edculas del primer grupo de carreras de pregrado diurno y vespertino del campus Valpara\u00edso<\/strong>, seg\u00fan acuerdo del Consejo Acad\u00e9mico del 3 de agosto de 2015 (<a href=\"http:\/\/www.upla.cl\/calendarioacademico\/pregrado-segun-acuerdo-del-consejo-academico-del-3-de-agosto-de-2015\/grupos\/carreras-grupo-1\/\">Revise aqu\u00ed listado<\/a>).<\/p>\n<p>Para ello, las vicerrector\u00edas Acad\u00e9mica y de Administraci\u00f3n y Finanzas informan las horarios, lugares y procedimientos de este proceso.<\/p>\n<h5><strong>Temas administrativos<\/strong><\/h5>\n<p class=\"alignnone\">Los estudiantes del primer grupo de carreras deben ingresar al <strong><a href=\"http:\/\/sistemas.upla.cl\/portal_estudiante\/wf_login.aspx\" target=\"_blank\" rel=\"noopener\">Portal del Estudiante<\/a><\/strong>, seleccionar la opci\u00f3n Matr\u00edculas y desde all\u00ed descargar e imprimir la <strong>\u00abHoja de Ruta\u00bb\u00a0<a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2015\/02\/HojaRuta.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-71276\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2015\/02\/HojaRuta.png\" alt=\"HojaRuta\" width=\"25\" height=\"25\" \/><\/a><\/strong>.<\/p>\n<p>Dicha documentaci\u00f3n estar\u00e1 disponible en el portal solo para los estudiantes de las carreras que les corresponde Matr\u00edcula en este per\u00edodo.<\/p>\n<p>Para el pago de los Aranceles de matr\u00edcula, se dispondr\u00e1 de las cajas institucionales y las sucursales del Banco de Chile.<\/p>\n<p>La hoja de ruta deber\u00e1 ser firmada y timbrada por el estudiante, ya sea por deudas arancelarias u otras deudas con nuestra instituci\u00f3n, tambi\u00e9n aquellos alumnos que deben firmar el pagar\u00e9 de Cr\u00e9dito Solidario. Dicha autorizaci\u00f3n se solicita en el Departamento de Aranceles.<\/p>\n<p>En el caso que el estudiante se encuentre con estatus distinto a ACTIVO, debe solicitar cambio de estado, en la Direcci\u00f3n de Gesti\u00f3n Curricular <strong>antes<\/strong> de pasar por Aranceles.<\/p>\n<p>Los m\u00f3dulos de aranceles atender\u00e1n entre el 23 y 25 de septiembre a los estudiantes de las carreras indicadas en calendario, en los siguientes horarios: 09.30 a 19.30 horas.<\/p>\n<p>Lugares:<\/p>\n<ul>\n<li>Gimnasio Anexo (Emisi\u00f3n de Hoja de Ruta, Cajas y m\u00f3dulos de informaci\u00f3n sobre rendiciones de Giro de Alumnos)<\/li>\n<li>Biblioteca secci\u00f3n Alta Demanda, segundo piso, acceso por rampa (Reprogramaci\u00f3n, Emisi\u00f3n de Letras y Firma de Pagar\u00e9 Fondo Solidario e Institucional, para este tr\u00e1mite se debe presentar fotocopia de c\u00e9dula de identidad vigente).<\/li>\n<\/ul>\n<h4><strong>INSCRIPCI\u00d3N DE ASIGNATURAS<\/strong><\/h4>\n<p>Luego de haber realizado la matr\u00edcula administrativa el estudiante podr\u00e1 inscribir sus asignaturas en l\u00ednea a trav\u00e9s del <strong><a href=\"http:\/\/sistemas.upla.cl\/portal_alumnos\/\" target=\"_blank\" rel=\"noopener\">Portal del Estudiante<\/a><\/strong>, seleccionar opci\u00f3n Matr\u00edculas y luego escoger el \u00edcono <a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2015\/02\/\u00edcono1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-71291\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2015\/02\/\u00edcono1.png\" alt=\"\u00edcono\" width=\"25\" height=\"25\" \/><\/a>\u00a0que se presenta en pantalla. En esta opci\u00f3n, debe seleccionar la o las asignaturas que le corresponde inscribir en el semestre, de acuerdo a su malla curricular. Siempre debe inscribir en primera instancia, los cursos atrasados.<\/p>\n<p>Una vez finalizada la inscripci\u00f3n de sus asignaturas, debe guardar e imprimir el <strong>Reporte de Inscripci\u00f3n de Asignaturas V\u00eda Web<\/strong>, como respaldo al procedimiento efectuado. Este proceso tiene que realizarlo cada vez que modifique su inscripci\u00f3n, la \u00faltima versi\u00f3n como la definitiva. El proceso de inscripci\u00f3n de asignaturas estar\u00e1 habilitado los d\u00edas de matr\u00edcula y modificaci\u00f3n de misma.<\/p>\n<p>El certificado de alumno regular estar\u00e1 disponible a trav\u00e9s del Portal del Estudiante, a partir del momento en que haya efectuado su Matr\u00edcula Administrativa y Acad\u00e9mica (ambas).<\/p>\n<p>Los estudiantes que hayan realizado matr\u00edcula de segunda parte de Seminario de T\u00edtulo, deber\u00e1n solicitar este certificado en la Direcci\u00f3n de Gesti\u00f3n Curricular con su copia de matr\u00edcula.<\/p>\n<p>Las fechas de los procesos de modificaci\u00f3n de matr\u00edcula, verificaci\u00f3n de matr\u00edcula y reporte final de matr\u00edcula, tiene que verificarlas en su calendario de actividades disponible <strong><a href=\"http:\/\/www.upla.cl\/calendarioacademico\/pregrado-segun-acuerdo-del-consejo-academico-del-3-de-agosto-de-2015\/grupos\/actividades-grupo-1\/\">aqu\u00ed<\/a><\/strong>.<\/p>\n<h4><strong>IMPORTANTE<\/strong><\/h4>\n<p>\u2022 Si usted no ha realizado la matr\u00edcula administrativa no podr\u00e1 inscribir los cursos correspondientes al semestre.<br \/>\n\u2022 Este semestre no habr\u00e1 matr\u00edcula fuera de plazo.<br \/>\n\u2022 Toda consulta relacionada con su matr\u00edcula acad\u00e9mica dirigirla a la casilla <a href=\"mailto:gestion.curricular@upla.cl\">gestion.curricular@upla.cl<\/a>.<\/p>\n<h4><strong>M\u00c1S INFORMACI\u00d3N<\/strong><\/h4>\n<p>Para mayor detalle, la Direcci\u00f3n de Gesti\u00f3n Curricular ha dispuesto de la \u00faltima versi\u00f3n actualizada de este instructivo. Descarga <a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2015\/09\/2015_0922_gestioncurricular_instructivomatricula_2015.pdf\">disponible aqu\u00ed<\/a>\u00a0en formato pdf (88 KB)<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre el 23 y 25 de septiembre deber\u00e1 realizar este proceso el primer grupo de carreras de pregrado diurno y vespertino del campus Valpara\u00edso, seg\u00fan acuerdo del Consejo Acad\u00e9mico.<\/p>\n","protected":false},"author":1,"featured_media":70743,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-76981","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"_links":{"self":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts\/76981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/comments?post=76981"}],"version-history":[{"count":0,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts\/76981\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/media?parent=76981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/categories?post=76981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/tags?post=76981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}