{"id":68301,"date":"2014-11-14T14:28:36","date_gmt":"2014-11-14T14:28:36","guid":{"rendered":"http:\/\/www.upla.cl\/noticias\/?p=68301"},"modified":"2014-11-14T14:28:36","modified_gmt":"2014-11-14T14:28:36","slug":"upla-entrego-merecido-reconocimiento-a-sus-mejores-alumnos","status":"publish","type":"post","link":"https:\/\/www.upla.cl\/facultad\/ingenieria\/2014\/11\/14\/upla-entrego-merecido-reconocimiento-a-sus-mejores-alumnos\/","title":{"rendered":"UPLA entreg\u00f3 merecido reconocimiento a sus mejores alumnos"},"content":{"rendered":"<p><a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2014\/11\/Becas-de-Honor-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-68315\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2014\/11\/Becas-de-Honor-1-300x200.jpg\" alt=\"Becas de Honor\" width=\"300\" height=\"200\" \/><\/a>En una instancia que permiti\u00f3 a los padres acercarse a la vida acad\u00e9mica de sus hijos, se transform\u00f3 la ceremonia en que los mejores estudiantes de la <strong>Universidad de Playa Ancha<\/strong> recibieron las <strong>Becas de Honor por Rendimiento Acad\u00e9mico<\/strong>.<\/p>\n<p>La ceremonia, que se realiza por tercer a\u00f1o consecutivo, es un reconocimiento p\u00fablico a los estudiantes de los cursos superiores de cada carrera que posean el mejor promedio de su promoci\u00f3n, sin haber reprobado ni homologado ninguna asignatura durante su vida acad\u00e9mica. Este a\u00f1o, se hicieron merecedores de este reconocimiento 146 estudiantes de pregrado, tanto diurno como vespertino, y del Instituto Tecnol\u00f3gico, los cuales tuvieron un destacado desempe\u00f1o acad\u00e9mico durante 2013.<\/p>\n<p>El <strong>rector Patricio Sanhueza Vivanco<\/strong>, que presidi\u00f3 el acto en el Aula Magna, entreg\u00f3 una triple felicitaci\u00f3n: a los propios estudiantes, por su excelencia acad\u00e9mica y haber merecido la Beca de Honor; a sus profesores, que han sabido formarlos de forma destacada; y a sus familiares y seres queridos, por apoyarlos en su paso por la universidad.<\/p>\n<p>Tambi\u00e9n la directora de Gesti\u00f3n Curricular, <strong>Catalina Rojas Mart\u00ednez<\/strong>, agradeci\u00f3 y valor\u00f3 a las familias por asistir a la ceremonia y motivar a los j\u00f3venes. Enfatiz\u00f3, sin embargo, el esfuerzo demostrado por los estudiantes para alcanzar este logro. \u00abNos sentimos orgullosos de otorgarle la <strong>Beca de Honor 2014<\/strong> a todos los estudiantes de nuestra universidad que se han destacado entre sus compa\u00f1eros\u00bb, asegur\u00f3.<\/p>\n<p><a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2014\/11\/Becas-de-Honor-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-68316\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2014\/11\/Becas-de-Honor-4-300x200.jpg\" alt=\"Becas de Honor\" width=\"300\" height=\"200\" \/><\/a>La ceremonia cont\u00f3 con un momento art\u00edstico y cultural, con m\u00fasica latinoamericana a cargo del grupo <strong>Wayna Kay<\/strong> (\u00abJuventud\u00bb, en quechua), formado por alumnos de <strong>Pedagog\u00eda en Educaci\u00f3n Musical<\/strong>. Tambi\u00e9n ellos felicitaron a sus compa\u00f1eros distinguidos y los reconocieron como un ejemplo para los estudiantes de la universidad.<\/p>\n<p>El solemne encuentro tuvo un ep\u00edlogo social, ya que autoridades, acad\u00e9micos, estudiantes y familiares pudieron compartir un caf\u00e9 en el domo ubicado junto a la Facultad de Arte. En esa instancia se multiplicaron los agradecimientos y felicitaciones por el reconocimiento a los destacados estudiantes de nuestra universidad.<\/p>\n<p>&nbsp;<\/p>\n<p>Im\u00e1genes de la entrega de reconocimientos se pueden ver <a href=\"http:\/\/www.upla.cl\/noticias\/?p=68284\">en esta p\u00e1gina<\/a>.<br \/>\nEl listado completo de los estudiantes que recibieron la Beca de Honor es el siguiente:<\/p>\n<p>&nbsp;<\/p>\n<p>[toggle title=\u00bbCampus San Felipe\u00bb state=\u00bbclose\u00bb ][table \u201c22\u201d not found \/]<br \/>\n[\/toggle]<\/p>\n<p>&nbsp;<\/p>\n<p>[toggle title=\u00bbCarreras vespertinas\u00bb state=\u00bbclose\u00bb ][table \u201c30\u201d not found \/]<br \/>\n[\/toggle]<\/p>\n<p>&nbsp;<\/p>\n<p>[toggle title=\u00bbFacultad de Arte\u00bb state=\u00bbclose\u00bb ][table \u201c20\u201d not found \/]<br \/>\n[\/toggle]<\/p>\n<p>&nbsp;<\/p>\n<p>[toggle title=\u00bbFacultad de Ciencias de la Actividad F\u00edsica y del Deporte\u00bb state=\u00bbclose\u00bb ][table \u201c27\u201d not found \/]<br \/>\n[\/toggle]<\/p>\n<p>&nbsp;<\/p>\n<p>[toggle title=\u00bbFacultad de Ciencias de la Educaci\u00f3n\u00bb state=\u00bbclose\u00bb ][table \u201c29\u201d not found \/]<br \/>\n[\/toggle]<\/p>\n<p>&nbsp;<\/p>\n<p>[toggle title=\u00bbFacultad de Ciencias de la Salud\u00bb state=\u00bbclose\u00bb ][table \u201c28\u201d not found \/]<br \/>\n[\/toggle]<\/p>\n<p>&nbsp;<\/p>\n<p>[toggle title=\u00bbFacultad de Ciencias Naturales y Exactas\u00bb state=\u00bbclose\u00bb ][table \u201c25\u201d not found \/]<br \/>\n[\/toggle]<\/p>\n<p>&nbsp;<\/p>\n<p>[toggle title=\u00bbFacultad de Ciencias Sociales\u00bb state=\u00bbclose\u00bb ][table \u201c24\u201d not found \/]<br \/>\n[\/toggle]<\/p>\n<p>&nbsp;<\/p>\n<p>[toggle title=\u00bbFacultad de Humanidades\u00bb state=\u00bbclose\u00bb ][table \u201c21\u201d not found \/]<br \/>\n[\/toggle]<\/p>\n<p>&nbsp;<\/p>\n<p>[toggle title=\u00bbFacultad de Ingenier\u00eda\u00bb state=\u00bbclose\u00bb ][table \u201c26\u201d not found \/]<br \/>\n[\/toggle]<\/p>\n<p>&nbsp;<\/p>\n<p>[toggle title=\u00bbInstituto Tecnol\u00f3gico Ignacio Domeyko\u00bb state=\u00bbclose\u00bb ][table \u201c23\u201d not found \/]<br \/>\n[\/toggle]<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Beca de Honor, que distingue a los j\u00f3venes con mejor promedio de su promoci\u00f3n, fue entregada frente a sus padres y compa\u00f1eros.<\/p>\n","protected":false},"author":1,"featured_media":68307,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-68301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"_links":{"self":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts\/68301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/comments?post=68301"}],"version-history":[{"count":0,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts\/68301\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/media?parent=68301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/categories?post=68301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/tags?post=68301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}