{"id":53812,"date":"2013-07-12T17:43:42","date_gmt":"2013-07-12T17:43:42","guid":{"rendered":"http:\/\/www.upla.cl\/noticias\/?p=53812"},"modified":"2013-07-12T17:43:42","modified_gmt":"2013-07-12T17:43:42","slug":"dan-a-conocer-plan-de-restauracion-de-la-reserva-nacional-el-yali","status":"publish","type":"post","link":"https:\/\/www.upla.cl\/facultad\/ingenieria\/2013\/07\/12\/dan-a-conocer-plan-de-restauracion-de-la-reserva-nacional-el-yali\/","title":{"rendered":"Dan a conocer Plan de Restauraci\u00f3n de la Reserva Nacional El Yali"},"content":{"rendered":"<p><a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2013\/07\/07.03.-Dan-a-conocer-Plan-de-Restauraci\u00f3n-de-la-Reserva-Nacional-El-Yali.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-53795\" alt=\"07.03.-Dan-a-conocer-Plan-de-Restauraci\u00f3n-de-la-Reserva-Nacional-El-Yali\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2013\/07\/07.03.-Dan-a-conocer-Plan-de-Restauraci\u00f3n-de-la-Reserva-Nacional-El-Yali.jpg\" width=\"485\" height=\"887\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fuente: Diario El Proa (www.elproa.cl), publicado el 3 de julio de 2013.<\/p>\n","protected":false},"author":1,"featured_media":53795,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-53812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"_links":{"self":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts\/53812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/comments?post=53812"}],"version-history":[{"count":0,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts\/53812\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/media?parent=53812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/categories?post=53812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/tags?post=53812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}