{"id":27749,"date":"2011-08-17T12:00:26","date_gmt":"2011-08-17T12:00:26","guid":{"rendered":"http:\/\/sitios.upla.cl\/contenidos\/?p=27749"},"modified":"2011-08-17T12:00:26","modified_gmt":"2011-08-17T12:00:26","slug":"tesis-sobre-efectos-del-tsunami-participara-en-congreso-de-ciencias-del-mar","status":"publish","type":"post","link":"https:\/\/www.upla.cl\/facultad\/ingenieria\/2011\/08\/17\/tesis-sobre-efectos-del-tsunami-participara-en-congreso-de-ciencias-del-mar\/","title":{"rendered":"Tesis sobre efectos del tsunami participar\u00e1 en Congreso de Ciencias del Mar"},"content":{"rendered":"<p>Para nadie es ajeno que el terremoto y posterior tsunami del 27 de febrero de 2010, dej\u00f3 a un pa\u00eds con muchas alteraciones en el plano familiar, social y geogr\u00e1fico. Hubo zonas costeras que fueron afectadas por la salida del mar y perturbaron significativamente el equilibrio ecol\u00f3gico.<\/p>\n<p>En esa l\u00ednea, el <strong>estudiante de Ingenier\u00eda Ambiental de la Universidad de Playa Ancha, Luis Urbina Parra<\/strong>, realiz\u00f3 su tesis de grado denominada: \u201c<strong>Variaci\u00f3n de los factores ambientales en las lagunas costeras de Llo-Lleo, San Antonio \u2013 Chile, producto del tsunami del 27\/02\/2010<\/strong>\u201d, que fue guiada por el profesor Manuel Contreras.<\/p>\n<p>El docente de la Facultad de Ingenier\u00eda explica que \u201cesta tesis fue parcialmente financiada por la Direcci\u00f3n General de Investigaci\u00f3n de la UPLA a trav\u00e9s del proyecto DGI TES\/01-2010; y, durante el a\u00f1o 2010, los resultados parciales de la misma fueron presentados en dos congresos cient\u00edficos y se gener\u00f3 una publicaci\u00f3n electr\u00f3nica con estos antecedentes\u00bb.<\/p>\n<p>A lo anterior se suma la aceptaci\u00f3n de este trabajo en el <a href=\"http:\/\/www.congresocienciasdelmar.cl\/\" target=\"_blank\" rel=\"noopener\">XXXI Congreso de Ciencias del Mar<\/a>, organizado por la Universidad de Valpara\u00edso, que se realiza entre el 16 y el 19 de agosto en Vi\u00f1a del Mar.<\/p>\n<p>Dicho estudio formar\u00e1 parte del Programa de Presentaciones Orales en el \u00e1rea de Medio Ambiente y Contaminaci\u00f3n II, que se efectuar\u00e1 ma\u00f1ana (jueves 18), a las 11.45 horas, en el Sal\u00f3n Chacabuco del Hotel O\u00b4Higgins. En la ocasi\u00f3n, Luis Urbina expondr\u00e1 junto a los acad\u00e9micos Manuel Contreras y Ximena Espinoza.<\/p>\n<p><strong>Tesis se incorporar\u00e1 a libro \u00abSan Antonio, El Bicentenario\u00bb<\/strong><\/p>\n<p>En la realizaci\u00f3n de este estudio Luis Urbina Parra cont\u00f3 con un valioso aporte: El Museo Municipal de Ciencias Naturales y Arqueolog\u00eda de San Antonio, dirigido por el profesor, conservador y curador Jos\u00e9 Luis Brito Montero.<\/p>\n<p>El Director de la Museo anunci\u00f3 la publicaci\u00f3n de un nuevo libro denominado \u201cSan Antonio, El Bicentenario\u201d, donde se podr\u00e1n revisar trabajos sobre los terremotos de 1985 y 2010, tsunami incluido, y c\u00f3mo afectaron dichos eventos naturales a la zona costera de la ciudad puerto, en el cual estar\u00e1 la tesis del estudiante de la UPLA.<\/p>\n<p>Paralelamente, el profesor Contreras comenta que junto a Urbina trabajan en la redacci\u00f3n de un manuscrito que relaciona los efectos ambientales post tsunami en las lagunas costeras de Llo-Lleo y en la Laguna Albufera de la Reserva Nacional El Yali, que esperan se transforme en una publicaci\u00f3n ISI.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El alumno de Ingenier\u00eda Ambiental, Luis Urbina Parra, expondr\u00e1 ma\u00f1ana (jueves 18) acerca de las consecuencias de este fen\u00f3meno natural en las lagunas costeras de Llo-Lleo. <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27749","post","type-post","status-publish","format-standard","hentry","category-novedades"],"_links":{"self":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts\/27749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/comments?post=27749"}],"version-history":[{"count":0,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/posts\/27749\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/media?parent=27749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/categories?post=27749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/ingenieria\/wp-json\/wp\/v2\/tags?post=27749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}