{"id":66287,"date":"2014-10-10T10:15:29","date_gmt":"2014-10-10T14:15:29","guid":{"rendered":"http:\/\/www.upla.cl\/noticias\/?p=66287"},"modified":"2014-10-10T10:15:29","modified_gmt":"2014-10-10T14:15:29","slug":"autoridades-apoyan-proceso-de-formacion-de-estudiantes-upla","status":"publish","type":"post","link":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/2014\/10\/10\/autoridades-apoyan-proceso-de-formacion-de-estudiantes-upla\/","title":{"rendered":"Autoridades apoyan proceso de formaci\u00f3n de estudiantes UPLA"},"content":{"rendered":"<p><strong><a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2014\/10\/Camila-Ruz-Pr\u00e1cticante-UPLA_Liceo-Alfredo-Nazar.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-66291\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2014\/10\/Camila-Ruz-Pr\u00e1cticante-UPLA_Liceo-Alfredo-Nazar-300x225.jpg\" alt=\"Camila Ruz, Pr\u00e1cticante UPLA_Liceo Alfredo Nazar\" width=\"300\" height=\"225\" \/><\/a>15 estudiantes de pedagog\u00eda de la Universidad de Playa Ancha<\/strong> desarrollan su pr\u00e1ctica en el <strong>Liceo Polit\u00e9cnico Alfredo Nazar de Playa Ancha<\/strong>. En ese marco el <strong>rector Patricio Sanhueza<\/strong> junto al <strong>decano de la Facultad de Ciencias de la Educaci\u00f3n, Luis Alberto D\u00edaz<\/strong>, visitaron a los j\u00f3venes y asistieron a algunas de sus clases.<\/p>\n<p>La m\u00e1xima autoridad universitaria explic\u00f3 que el proceso de pr\u00e1cticas es fundamental en la formaci\u00f3n de un profesor, por lo que quisieron verificar en terreno c\u00f3mo se est\u00e1n desarrollando estas actividades formativas.<\/p>\n<p>\u201cHemos querido, junto al decano Luis Alberto D\u00edaz, conocer cu\u00e1nto est\u00e1n aportando nuestros j\u00f3venes en los procesos de aprendizaje, las metodolog\u00edas que est\u00e1n usando para impactar mucho m\u00e1s en el crecimiento de los alumnos en todos los aspectos, cu\u00e1l es la motivaci\u00f3n que est\u00e1n imprimiendo al principio de la clase y si se logran efectivamente los aprendizajes o no en la pr\u00e1ctica real. Nuestro objetivo es justamente apoyar este proceso y apoyar a nuestros estudiantes para que cada d\u00eda les vaya mejor en la formaci\u00f3n profesional\u201d, dijo el <strong>rector Sanhueza<\/strong>.<\/p>\n<p>Para cumplir con ese objetivo participaron como observadores de la clase de la <strong>estudiante de Pedagog\u00eda en Historia y Geograf\u00eda, Camila Ruz<\/strong>, para luego reunirse con los j\u00f3venes que realizan su pr\u00e1ctica profesional y conocer su parecer respecto a esta experiencia en el liceo playanchino.<\/p>\n<p><a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2014\/10\/Luis-Pereira-V\u00e1squez_director-Liceo-Alfredo-Nazar.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-66289\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2014\/10\/Luis-Pereira-V\u00e1squez_director-Liceo-Alfredo-Nazar-150x150.jpg\" alt=\"Luis-Pereira-V\u00e1squez_director-Liceo-Alfredo-Nazar\" width=\"150\" height=\"150\" \/><\/a>Respecto a la visita de las autoridades de la UPLA <strong>el director del establecimiento, Luis Pereira V\u00e1squez<\/strong>, manifest\u00f3 \u201cque para un practicante es un privilegio que el rector venga a observar una clase, creo que quedar\u00e1 para la historia de esos estudiantes en su carrera profesional\u201d.<\/p>\n<p>Agreg\u00f3 que como miembro de la Corporaci\u00f3n Siglo XXI mantienen una relaci\u00f3n muy directa con la universidad y sus estudiantes. Con estos \u00faltimos se ha establecido un nexo especial.<\/p>\n<p>\u201cSiempre tenemos mucha gente de la UPLA, actualmente hay 15 estudiantes realizando su pr\u00e1ctica y la evaluaci\u00f3n que hago es muy buena porque los alumnos que salen de la universidad tienen una comprensi\u00f3n mucho m\u00e1s exacta de la realidad social. Por lo tanto enganchan muy bien con este tipo de liceos. As\u00ed que nosotros estamos encantados con ellos\u201d, resalt\u00f3 el directivo.<\/p>\n<p>Anunci\u00f3, adem\u00e1s, que ha conversado con el rector Sanhueza para iniciar un trabajo de investigaci\u00f3n con los estudiantes de \u00faltimo a\u00f1o de la carrera de Pedagog\u00eda en Historia y Geograf\u00eda, con el fin de que puedan hacer una tesis sobre la historia de este emblem\u00e1tico liceo.<\/p>\n<div class=\"et_pb_slider et_pb_slider_fullwidth_off et_pb_gallery_post_type\">\n\t\t\t\t<div class=\"et_pb_slides\">\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El rector Sanhueza junto al decano Luis Alberto D\u00edaz visitaron a los j\u00f3venes que realizan su pr\u00e1ctica pedag\u00f3gica en el Liceo Polit\u00e9cnico Alfredo Nazar de Playa Ancha.<\/p>\n","protected":false},"author":1,"featured_media":66294,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-66287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades-de-la-facultad"],"_links":{"self":[{"href":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/wp-json\/wp\/v2\/posts\/66287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/wp-json\/wp\/v2\/comments?post=66287"}],"version-history":[{"count":0,"href":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/wp-json\/wp\/v2\/posts\/66287\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/wp-json\/wp\/v2\/media?parent=66287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/wp-json\/wp\/v2\/categories?post=66287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/wp-json\/wp\/v2\/tags?post=66287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}