{"id":58203,"date":"2013-12-14T15:26:12","date_gmt":"2013-12-14T19:26:12","guid":{"rendered":"http:\/\/sitios.upla.cl\/contenidos\/?p=56830"},"modified":"2013-12-14T15:26:12","modified_gmt":"2013-12-14T19:26:12","slug":"egresado-upla-entre-los-100-grandes-profesores-para-chile","status":"publish","type":"post","link":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/2013\/12\/14\/egresado-upla-entre-los-100-grandes-profesores-para-chile\/","title":{"rendered":"Egresado UPLA entre los 100 grandes profesores para Chile"},"content":{"rendered":"<p><a href=\"http:\/\/sitios.upla.cl\/contenidos\/wp-content\/uploads\/2013\/12\/Rodrigo-Navarro_100-grandes-profesores-para-Chile.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-56832\" alt=\"Rodrigo-Navarro_100-grandes-profesores-para-Chile\" src=\"http:\/\/sitios.upla.cl\/contenidos\/wp-content\/uploads\/2013\/12\/Rodrigo-Navarro_100-grandes-profesores-para-Chile-300x225.jpg\" width=\"300\" height=\"225\" \/><\/a> <a href=\"http:\/\/sitios.upla.cl\/contenidos\/wp-content\/uploads\/2013\/12\/Rodrigo-Navarro_100-grandes-profesores-para-Chile1.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-56833\" alt=\"Rodrigo-Navarro_100-grandes-profesores-para-Chile1\" src=\"http:\/\/sitios.upla.cl\/contenidos\/wp-content\/uploads\/2013\/12\/Rodrigo-Navarro_100-grandes-profesores-para-Chile1-300x225.jpg\" width=\"300\" height=\"225\" \/><\/a>En el Palacio de La Moneda fueron <strong>distinguidos 100 profesores de todo Chile<\/strong> que est\u00e1n marcando una diferencia y haciendo una contribuci\u00f3n y una apuesta importante a la educaci\u00f3n de nuestro pa\u00eds.<\/p>\n<p>Uno de ellos, fue el <strong>egresado de Pedagog\u00eda en Educaci\u00f3n B\u00e1sica de la Universidad de Playa Ancha Rodrigo Navarro Ojeda<\/strong>, quien fue reconocido por el innovador proyecto educativo \u201cMatem\u00e1tica en Familia\u201d que desarrolla hace m\u00e1s de tres a\u00f1os en el colegio Bosquemar de Puerto Montt.<\/p>\n<p>Por medio de talleres el docente involucra a padres y apoderados en el proceso de ense\u00f1anza-aprendizaje de sus hijos, metodolog\u00eda que ha permitido mejorar la comprensi\u00f3n de la asignatura y los resultados acad\u00e9micos de ni\u00f1os y ni\u00f1as de quinto a octavo b\u00e1sico.<\/p>\n<p>\u201cEste reconocimiento, compartido con mis estudiantes y apoderados, me alienta a seguir creyendo en los cambios, en mi trabajo, en hacer cosas distintas y \u00fatiles que ayuden a mejorar nuestra sociedad desde la mirada de un profesor dispuesto\u201d, dijo Navarro sobre la distinci\u00f3n.<\/p>\n<p>A\u00f1adi\u00f3 que los profesores deben ser agentes de cambio en sus centros educativos, aunque encuentren dificultades. \u201cAnte ellas, deben buscar soluciones a trav\u00e9s de la elaboraci\u00f3n de proyectos y estrategias que encanten y motiven a sus estudiantes. Los logros adem\u00e1s no vienen de inmediato, hay que ser paciente, sencillo, humilde para compartir las experiencias y aportar colaborando con otros docentes\u201d, sugiri\u00f3 el egresado UPLA.<\/p>\n<p>Cabe destacar que \u00e9ste no es el primer reconocimiento que recibe por su labor docente, ya que su proyecto result\u00f3 seleccionado entre las diez iniciativas escolares, a nivel nacional, en el <strong>VI Concurso 2013 de la Red de Escuelas L\u00edderes. Educaci\u00f3n de Calidad contra la Pobreza, de la Fundaci\u00f3n Chile<\/strong>.<\/p>\n<p><strong>SOBRE CONCURSO 100 GRANDES PROFESORES PARA CHILE<\/strong><\/p>\n<p>A este certamen \u2013organizado por el Ministerio de Educaci\u00f3n, en conjunto con Elige Educar y el diario La Cuarta- postularon 1.424 maestros, entre los que se cuentan profesores de educaci\u00f3n de p\u00e1rvulos, educaci\u00f3n b\u00e1sica, media, media t\u00e9cnico profesional, especial, de adultos, intercultural y de establecimientos rurales.<\/p>\n<p>La decisi\u00f3n final fue tomada por un jurado compuesto por: Carolina Schmidt, Ministra de Educaci\u00f3n; Paula Pinedo, directora del CPEIP; Ernesto Schiefelbein, Premio nacional de Educaci\u00f3n; Ver\u00f3nica Monsalve, Colegio de Profesores; Luz Mar\u00eda Budge, presidenta del Consejo de la Agencia de la Calidad; M\u00f3nica Jim\u00e9nez, exministra de Educaci\u00f3n; Hern\u00e1n Hochschild, director ejecutivo Elige Educar; Patricia Schaulsohn, de Educaci\u00f3n 2020; Sergio Maraboli, director de La Cuarta; Ceina Iberti, coordinadora de Proyectos de Educaci\u00f3n Grupo Copesa; Teresa Lagos, directora del Liceo Bicentenario Italia; y Francisca Reyes, estudiante beneficiaria de Beca Vocaci\u00f3n de Profesor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rodrigo Navarro Ojeda fue reconocido por el innovador proyecto educativo \u201cMatem\u00e1tica en Familia\u201d que desarrolla hace m\u00e1s de tres a\u00f1os en el colegio Bosquemar de Puerto Montt. <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-58203","post","type-post","status-publish","format-standard","hentry","category-novedades-de-la-facultad"],"_links":{"self":[{"href":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/wp-json\/wp\/v2\/posts\/58203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/wp-json\/wp\/v2\/comments?post=58203"}],"version-history":[{"count":0,"href":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/wp-json\/wp\/v2\/posts\/58203\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/wp-json\/wp\/v2\/media?parent=58203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/wp-json\/wp\/v2\/categories?post=58203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upla.cl\/facultad\/cienciaseducacion\/wp-json\/wp\/v2\/tags?post=58203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}