{"id":106498,"date":"2017-09-29T12:11:28","date_gmt":"2017-09-29T15:11:28","guid":{"rendered":"http:\/\/www.upla.cl\/noticias\/?p=106498"},"modified":"2018-09-07T18:32:34","modified_gmt":"2018-09-07T21:32:34","slug":"atletas-upla-dominaron-la-segunda-fecha-de-la-ldes-en-damas-y-en-varones","status":"publish","type":"post","link":"https:\/\/www.upla.cl\/desarrolloestudiantil\/2017\/09\/29\/atletas-upla-dominaron-la-segunda-fecha-de-la-ldes-en-damas-y-en-varones\/","title":{"rendered":"Atletas UPLA dominaron la segunda fecha de la LDES en damas y en varones"},"content":{"rendered":"<p><a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/09\/atletismo_upla_3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-106501\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/09\/atletismo_upla_3-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a>La pista atl\u00e9tica del estadio El\u00edas Figueroa Brander fue el escenario para la realizaci\u00f3n de la segunda fecha del torneo de atletismo <strong>Ligas Deportivas Educaci\u00f3n (LDES)<\/strong>, evento que cont\u00f3 con la presencia de los mejores atletas de la regi\u00f3n.<br \/>\n<strong>Yetsem\u00edn Gonz\u00e1lez, estudiante de Pedagog\u00eda en Educaci\u00f3n F\u00edsica de la Universidad de Playa Ancha<\/strong>, ganadora de los 1500 metro planos (4 minutos, 49 segundos y 77 <a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/09\/atletismo_upla_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-106499\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/09\/atletismo_upla_1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a>cent\u00e9simas) y de los 10.000 mil metros (37 minutos, 46 segundos y 86 cent\u00e9simas) afirm\u00f3 estar feliz por lo conseguido: \u201cEs importante para m\u00ed estar nuevamente en las Finales Nacionales, donde cada a\u00f1o el nivel competitivo universitario crece, y me siento a la altura de obtener un buen resultado\u201d.<br \/>\nGonz\u00e1lez, agreg\u00f3 que su objetivo \u201ces estar entre las <a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/09\/atletismo_upla_4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-106502\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/09\/atletismo_upla_4-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a>tres mejores a nivel nacional en dos pruebas, disfrutar del evento y apoyar al equipo\u201d.<br \/>\n\u201cPara m\u00ed ser seleccionada de la rama de atletismo UPLA es sin\u00f3nimo de alegr\u00eda, ya que detr\u00e1s de eso hay muchas horas de entrenamientos sumado a las cargas acad\u00e9micas, donde veo a mis compa\u00f1eros trabajando por sus objetivos con seriedad, responsabilidad y entrega, sintiendo el apoyo del entrenador en cada momento\u201d, sentenci\u00f3 Gonz\u00e1lez.<br \/>\n<a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/09\/atletismo_upla_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-106500\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/09\/atletismo_upla_2-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a>En tanto, <strong>Patricio Colarte<\/strong>, seleccionado de la UPLA y ganador de los 110 metros vallas (15 segundos con 54 cent\u00e9simas) y del relevo 4 x 100 (43 segundos y 39 cent\u00e9simas) expres\u00f3: \u201cFue una carrera dura, debido a que la \u00faltima vez que corr\u00ed sufr\u00ed una lesi\u00f3n, las condiciones no fueron las mejores, pero espero tratar de llegar de la mejor manera al nacional, la idea es revalidar el t\u00edtulo conseguido el a\u00f1o pasado\u201d.<br \/>\n<strong><a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/09\/L-Plaza.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-106507\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/09\/L-Plaza-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a>Liliana Plaza, estudiante de Pedagog\u00eda en Educaci\u00f3n F\u00edsica,<\/strong> ganadora de los 100 metros planos( 13 segundos y 4 cent\u00e9simas) y 200 metros planos (26 segundos y 39 cent\u00e9simas ), dijo: \u201cClasificar era algo esperado, debido a todo el entrenamiento que hay detr\u00e1s, adem\u00e1s de hacerlo como la mejor de la regi\u00f3n otro a\u00f1o m\u00e1s, ratifica que estamos haciendo bien las cosas con mi entrenador Mat\u00edas Barrera\u201d.<br \/>\nPlaza agreg\u00f3: \u201cLas metas son altas, el a\u00f1o 2015 en Chill\u00e1n gan\u00e9 las Finales Nacionales y el 2016 tuve doble p\u00f3dium en 100 y 200 metros planos, as\u00ed es que en Talca voy por la medalla\u201d.<\/p>\n<h5><strong>Honor de vestir la camiseta UPLA<\/strong><\/h5>\n<p><strong><a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/09\/atletismo_upla_8.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-106505\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/09\/atletismo_upla_8-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a>Catalina Valenzuela, estudiante de Terapia Ocupacional<\/strong> ganadora en la prueba de la bala (10 metros y 15 cent\u00edmetros) y la jabalina (37 metros y 96 cent\u00edmetros), manifest\u00f3 su alegr\u00eda por haber clasificado a las Finales Nacionales que se realizar\u00e1n en la regi\u00f3n del Maule: \u201cPara m\u00ed es muy importante, ya que es mi primer a\u00f1o universitario, y espero acercarme a mis mejores marcas y dar puntos a mi universidad\u201d.<br \/>\nDijo tambi\u00e9n que \u201ces un honor y satisfacci\u00f3n representar a mi universidad, as\u00ed es que lo dar\u00e9 todo por representarla de la mejor manera posible\u201d.<br \/>\n<strong>Roberto Jorquera, estudiante de Tecnolog\u00eda en Deportes<\/strong>, manifest\u00f3 su alegr\u00eda por haber conseguido el primer lugar en la jabalina, con el que inscribi\u00f3 su nombre en las Finales Nacionales (45 metros y 65 cent\u00edmetros). \u201cPara m\u00ed es una instancia bastante importante, porque es la cita universitaria m\u00e1xima en el pa\u00eds, la idea es ir a competir y ganar las tres medallas. Dentro de todo, pretendo mejorar mi marca de aqu\u00ed a la fecha del nacional para disputar las medallas en Talca\u201d.<br \/>\nEl atleta cont\u00f3 que se ha encari\u00f1ado con la universidad. \u201cLa idea es dejar el nombre de la UPLA en lo m\u00e1s alto y representarla de la mejor manera posible, porque es un orgullo, sobre todo en el \u00faltimo a\u00f1o\u201d.<br \/>\nMarcia Cueto, estudiante de Mag\u00edster en Ciencias de la Actividad F\u00edsica y del Deporte en la UPLA, gan\u00f3 el lanzamiento de la jabalina (39 metros y 59 cent\u00edmetros) sostuvo: \u201cPara m\u00ed este nacional es simb\u00f3lico, porque ser\u00eda mi \u00faltimo a\u00f1o compitiendo por la UPLA. Mi meta en el nacional es subirme al podio con una marca superior a los 40 metros\u201d.<br \/>\n<a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/09\/atletismo_upla_5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-106503\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/09\/atletismo_upla_5-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a>Cueto agreg\u00f3: \u201cQuiero dar las gracias a mi entrenador Sergio Galdames y a la UPLA por permitirme vestir su camiseta durante estos tres a\u00f1os\u201d.<br \/>\n<strong>B\u00e1rbara Sof\u00eda Vega, estudiante de Pedagog\u00eda en Educaci\u00f3n F\u00edsica<\/strong>, ganadora de salto alto con (1.45) y tercera en los 110 metros vallas con (21 segundos y 22 cent\u00e9simas), realiz\u00f3 un an\u00e1lisis positivo sobre su participaci\u00f3n en el marco de la segunda fecha de la LDES, dej\u00e1ndola a un paso de las Finales Nacionales. \u201cSiempre ha sido un orgullo y una enorme felicidad participar y representar a la universidad, que me dio una nueva oportunidad para realizar este deporte que tanto amo, espec\u00edficamente mi entrenador Sergio Galdames, quien ha estado conmigo durante todos estos a\u00f1os apoy\u00e1ndome y orient\u00e1ndome en todo lo que conlleva est\u00e1 pr\u00e1ctica deportiva\u201d.<br \/>\nVega se refiri\u00f3 al sentimiento de identidad y compromiso con la UPLA, que se incrementa cada a\u00f1o. \u201cPertenecer a una rama deportiva genera una diversidad de beneficios, comenzando por la experiencia, aprendizaje y perfeccionamiento del deporte. Dentro del equipo adem\u00e1s se forja una uni\u00f3n exquisita en donde el compa\u00f1erismo y la amistad son motivos por los cuales el atletismo de la UPLA se destaca. La selecci\u00f3n no solo es conocida por los logros individuales, sino que marca presencia, se impone como equipo y marca la diferencia en cualquier lado al que vamos\u201d.<br \/>\n<strong><a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/09\/atletismo_upla_9.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-106506\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/09\/atletismo_upla_9-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a>Catherine Cort\u00e9s, estudiante de Mag\u00edster en Evaluaci\u00f3n Educacional<\/strong>, consigui\u00f3 el segundo lugar en los 1500 (5 minutos, 19 segundos y 96 cent\u00e9simas) y los 10.000 metros planos (41 minutos, 13 segundos y 96 cent\u00e9simas). \u201cPara m\u00ed es una satisfacci\u00f3n enorme lograr clasificar a la instancia nacional, ya que el ritmo que llevo d\u00eda a d\u00eda, con el trabajo, los estudios y la maternidad, no me permiten entrenar con la dedicaci\u00f3n que quisiera, pero a pesar de ello, me esfuerzo y trato de ordenar mis tiempos para lograr hacer todo de buena manera\u201d.<br \/>\nAgreg\u00f3 Cort\u00e9s que su prioridad para el nacional son los 3000 obst\u00e1culos y mejorar el cuarto lugar del a\u00f1o pasado.\u00a0\u201cAgradezco el apoyo de mi entrenador Fabi\u00e1n Barrera, quien ha sido parte importante de este proceso, porque hemos logrado bajar todas mis marcas este a\u00f1o. Para m\u00ed ser parte de la UPLA significa aportar con un granito de arena en los logros deportivos que esta casa de estudios ha tenido en los \u00faltimos a\u00f1os, y que la ha posicionado dentro del atletismo universitario a nivel regional y nacional. Estoy muy agradecida de la acogida, tanto del entrenador de \u00e9sta (Sergio Galdames) como del equipo en general, sentenci\u00f3 Cort\u00e9s.<br \/>\n<strong><a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/09\/atletismo_upla_7.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-106504\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/09\/atletismo_upla_7-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a>Sergio Galdames, entrenador de atletismo damas y varones de la Universidad de Playa Ancha<\/strong>, realiz\u00f3 un an\u00e1lisis positivo sobre el desempe\u00f1o de sus dirigidos: \u201cHa sido un campeonato muy exitoso para nosotros, donde hemos conseguido buenas marcas que permiten hacer las clasificaciones, al menos entre 10 a 12 atletas que asistir\u00e1n a las Finales Nacionales\u201d.<br \/>\n\u201cEste a\u00f1o se dio que estamos en la curva m\u00e1s alta \u2013coment\u00f3 el entrenador. En el primer semestre lo ganamos todo. Esto es la continuidad del trabajo, el aporte que hacen los atletas con sus entrenadores internos, que es muy valioso y el gran grueso del equipo que son dirigidos por m\u00ed, donde han tenido una etapa de maduraci\u00f3n, sobre todo, en los dos \u00faltimos a\u00f1os se ha ido consolidando el trabajo\u201d.<br \/>\nGaldames explic\u00f3 que son 9 a\u00f1os de trabajo, con dos ciclos. Son ya dos a\u00f1os de participaciones en las Finales Nacionales muy fuertes, donde la UPLA ha estado dentro de las cinco mejores del pa\u00eds, de un universo de 50 casas de estudios. El desaf\u00edo ser\u00e1 mantenerse, pero va depender de la cantidad de clasificados que se tenga.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con un total de 14 oros, 9 en damas y 5 en varones, la selecci\u00f3n consigui\u00f3 las marcas necesarias para clasificar a las Finales Nacionales, evento que se realizar\u00e1 en la regi\u00f3n del Maule.<\/p>\n","protected":false},"author":2,"featured_media":106500,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[43,18,8],"tags":[],"class_list":["post-106498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-estudiantes","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/posts\/106498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/comments?post=106498"}],"version-history":[{"count":0,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/posts\/106498\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/media?parent=106498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/categories?post=106498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/tags?post=106498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}