{"id":102579,"date":"2017-06-28T09:23:05","date_gmt":"2017-06-28T13:23:05","guid":{"rendered":"http:\/\/www.upla.cl\/noticias\/?p=102579"},"modified":"2018-09-07T18:34:50","modified_gmt":"2018-09-07T21:34:50","slug":"seleccion-de-balonmano-damas-upla-logro-subcampeonato-en-los-juegos-universitarios-navales","status":"publish","type":"post","link":"https:\/\/www.upla.cl\/desarrolloestudiantil\/2017\/06\/28\/seleccion-de-balonmano-damas-upla-logro-subcampeonato-en-los-juegos-universitarios-navales\/","title":{"rendered":"Selecci\u00f3n de balonmano damas UPLA logr\u00f3 subcampeonato en los Juegos Universitarios Navales"},"content":{"rendered":"<p><a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/06\/subcampeon_jnavales_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-102582\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/06\/subcampeon_jnavales_1.jpg\" alt=\"\" width=\"640\" height=\"427\" \/><\/a>Un meritorio segundo lugar en el marco de la <strong>XXVII versi\u00f3n de los Juegos Universitarios Navales<\/strong>, logr\u00f3 la selecci\u00f3n de balonmano damas de la <strong>Universidad de Playa Ancha<\/strong>, que consigui\u00f3 un total de cuatro triunfos, un empate y dos derrotas, logrando la suma de 191 goles a favor y 186 en contra, y registrando \u00a0una diferencia de m\u00e1s cinco.<br \/>\n<a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/06\/subcampeon_jnavales.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-102581\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/06\/subcampeon_jnavales-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a>Al revisar su campa\u00f1a, la UPLA en la fase de clasificaci\u00f3n venci\u00f3 a la Universidad Andr\u00e9s Bello por 39-23, a la Universidad de Valpara\u00edso por 31-24 y super\u00f3 a la Universidad T\u00e9cnica Federico Santa Mar\u00eda-Casa Central por 17-12. As\u00ed tambi\u00e9n registr\u00f3 un empate a 29 goles ante la Universidad Vi\u00f1a del Mar, y tuvo una sola derrota ante la Pontificia Universidad Cat\u00f3lica de Valpara\u00edso por 41-24. Accedi\u00f3 a semifinales del torneo, donde enfrent\u00f3 a la UVM, la super\u00f3 por 27-24, y la final la perdi\u00f3 por 34-23.<br \/>\n<strong>Yolanda Salgado, estudiante de Pedagog\u00eda en Educaci\u00f3n Diferencial del campus San Felipe<\/strong>, tuvo <a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/06\/yolanda_salgado.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-102585\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/06\/yolanda_salgado-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a>palabras de elogio para sus compa\u00f1eros que se esforzaron por llegar lo m\u00e1s alto posible en el campeonato: \u201cEn el torneo fuimos de menos a m\u00e1s, donde estuvimos d\u00e9biles en el inicio. Sin embargo, con el pasar de los partidos fuimos mejorando y nos compenetramos mejor. Por lo tanto, conseguir un subcampeonato no es tan malo, a pesar que uno aspira a ser primero\u201d.<br \/>\nSalgado, al ser consultada sobre las metas que pretenden alcanzar, fue clara en se\u00f1alar: \u201cEn el segundo semestre, tenemos la misi\u00f3n de clasificar al Fenaude Nacional de balonmano, donde esperamos tener una buena participaci\u00f3n\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gran avance respecto del a\u00f1o pasado en que el equipo de Playa Ancha se qued\u00f3 con la cuarta posici\u00f3n del campeonato.<\/p>\n","protected":false},"author":2,"featured_media":102582,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[43,18,8],"tags":[],"class_list":["post-102579","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-estudiantes","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/posts\/102579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/comments?post=102579"}],"version-history":[{"count":0,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/posts\/102579\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/media?parent=102579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/categories?post=102579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/tags?post=102579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}