{"id":101905,"date":"2017-06-14T09:00:47","date_gmt":"2017-06-14T13:00:47","guid":{"rendered":"http:\/\/www.upla.cl\/noticias\/?p=101905"},"modified":"2018-09-07T18:34:50","modified_gmt":"2018-09-07T21:34:50","slug":"dd-hh-memoria-y-literatura-se-conjugaron-en-cierre-del-programa-dialogos-en-movimiento-en-upla","status":"publish","type":"post","link":"https:\/\/www.upla.cl\/desarrolloestudiantil\/2017\/06\/14\/dd-hh-memoria-y-literatura-se-conjugaron-en-cierre-del-programa-dialogos-en-movimiento-en-upla\/","title":{"rendered":"DD.HH, memoria y literatura se conjugaron en cierre del programa Di\u00e1logos en Movimiento en UPLA"},"content":{"rendered":"<p>Todo un \u00e9xito result\u00f3 el cierre del ciclo de conversatorios enmarcados en el programa \u201c<strong>Di\u00e1logos en movimiento<\/strong>\u201d, actividad conjunta realizada entre la <strong>Universidad de Playa Ancha, el Ministerio de Educaci\u00f3n y el\u00a0Consejo Nacional de la Cultura y las Artes<\/strong>.<br \/>\n<a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/06\/Marcos-Aravena.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-101908\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/06\/Marcos-Aravena-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" \/><\/a>En esta oportunidad, la invitada fue la escritora <strong>Lola Larra<\/strong> quien con su libro \u201c<strong>Sprinters. Los ni\u00f1os de Colonia Dignidad\u201d (2016)<\/strong>, tuvo como objetivo entregar distintas estrategias y metodolog\u00edas de mediaci\u00f3n lectora a estudiantes de P<strong>edagog\u00eda en Castellano<\/strong>.<br \/>\nEl coordinador de esta actividad, el <strong>profesor Marcos Aravena Cuevas del Departamento de Literatura<\/strong>, sostuvo que la experiencia ha sido bastante favorable. \u201cLos estudiantes han sacado bastante provecho a estas instancias ya que entregamos herramientas concretas que ellos utilizan en su vida profesional. Es relevante que ellos manejen distintas metodolog\u00edas de mediaci\u00f3n lectora y acercar de manera eficaz a los alumnos tanto de b\u00e1sica como de media a distintas obras de la literatura universal\u201d.<br \/>\nA su vez el <strong>bibliotec\u00f3logo Sebasti\u00e1n Santander<\/strong>, <strong>mediador de lectura en estas jornadas del Consejo de la Cultura<\/strong>, agreg\u00f3 que \u201cha sido un proceso muy interesante abordar la tem\u00e1tica de la mediaci\u00f3n y que no se trabaja com\u00fanmente en la academia. El diagn\u00f3stico que vemos desde afuera no es tan errado y los estudiantes necesitan acercarse mucho m\u00e1s al \u00e1rea de la mediaci\u00f3n y complementarla con la educaci\u00f3n\u201d.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-101907\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/06\/Dialogos_Lola_Larra11-300x212.jpg\" alt=\"\" width=\"300\" height=\"212\" \/><br \/>\nSantander explic\u00f3 la importancia de cautivar a los futuros lectores a trav\u00e9s de temas relevantes para nuestra sociedad. \u201cLa mediaci\u00f3n finalmente es un oficio que permite compartir la lectura sin tener la preocupaci\u00f3n necesaria de la evaluaci\u00f3n, del registro o la evidencia, pero s\u00ed permite la lectura efectiva y que las personas que van a leer los textos que se proponen se acerquen de manera l\u00fadica y puedan generar hitos en su vida en torno a la lectura y que esta, no transform\u00e1ndose en algo que rechacen\u201d.<br \/>\nPara <strong>Aravena<\/strong>, el contenido de la jornada en torno a la memoria es un tema predominante en la literatura chilena al ser \u201cun periodo que se necesita pensar de manera ficcional con el pasado reciente. La novela de <strong>Lola Larra<\/strong> muestra en un formato cr\u00f3nica-novela todas las vicisitudes que vivieron algunos ni\u00f1os denominados \u201csprinters\u201d dentro del contexto autoritario de Colonia Dignidad\u201d.<\/p>\n<h5><strong>La b\u00fasqueda de la memoria en palabras de Lola Larra<\/strong><\/h5>\n<p><a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/06\/Dialogos_Lola_Larra1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-101906\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/06\/Dialogos_Lola_Larra1-300x212.jpg\" alt=\"\" width=\"300\" height=\"212\" \/><\/a>En una mezcla de cr\u00f3nica, ficci\u00f3n y storyboards, \u201c<strong>Sprinters. Los ni\u00f1os de Colonia Dignidad<\/strong>\u201d se enmarca dentro de las tendencias contempor\u00e1neas de la literatura al ser un h\u00edbrido gen\u00e9rico, no solo con lo que tiene que ver netamente con la redacci\u00f3n ficcional narrativa, sino tambi\u00e9n con la imagen y el testimonio real del hecho que aconteci\u00f3. El libro refleja estas t\u00e9cnicas propias de la contemporaneidad literaria\u00bb.<br \/>\n<strong>\u00bfC\u00f3mo naci\u00f3 la idea de esta novela?<\/strong><br \/>\nCuando viv\u00eda en Madrid ya me interesaba todo lo relacionado a Colonia Dignidad y al volver a Chile indagu\u00e9 durante diez a\u00f1os entre juicios, documentos y notas de prensa\u2026 en fin, todo lo que ten\u00eda a mano. Como soy periodista de profesi\u00f3n realic\u00e9 a su vez numerosas entrevistas a colonos, visit\u00e9 Colonia Dignidad dos veces e interactu\u00e9 con personas que aun viven ah\u00ed. Despu\u00e9s segu\u00ed la ruta a colonos que se hab\u00edan fugado del lugar, compart\u00ed mucho tiempo con ellos y presenci\u00e9 c\u00f3mo se reinsertaban en la sociedad despu\u00e9s de que hab\u00edan sido sometidos a un sistema totalitario como el de Paul Sch\u00e4fer\u00bb.<br \/>\n<strong>\u00bfC\u00f3mo fue mezclar la ficci\u00f3n, la cr\u00f3nica period\u00edstica, los storyboards y los DD.HH y que todo esto encajara en su libro?<\/strong><br \/>\n\u00abFue bastante natural. En un principio no sab\u00eda qu\u00e9 iba a realizar con toda esta informaci\u00f3n; si un libro de ficci\u00f3n, si una cr\u00f3nica period\u00edstica, un gui\u00f3n para una pel\u00edcula o si iba a ser una novela. Al final Sprinters. Los Ni\u00f1os de Colonia Dignidad\u00a0 es un poco de todo eso. Cuando realmente sent\u00ed que el libro iba a funcionar y era posible hacerlo es cuando apareci\u00f3 la voz y ojos de la colonia Lutguarda, personaje principal de la novela.<br \/>\nArm\u00e9 un rompecabezas con todo lo que recab\u00e9. Mis amigos dec\u00edan que parec\u00eda un DJ mezclando distintas cosas que ven\u00edan de todos lados, fue complejo pero tuve un gran editor cosa que los autores debemos agradecer\u00bb.<br \/>\n<strong>\u00bfY la relevancia de la memoria?<\/strong><br \/>\n\u00abEn el libro cuento que las declaraciones de estos ni\u00f1os que vivieron en Colonia Dignidad eran contradictorias, me pregunt\u00e9 cu\u00e1l es la verdad y c\u00f3mo la memoria nos enga\u00f1a y ante esto la posibilidad de contar la verdad de todo. Me di cuenta que nunca se podr\u00e1 saber toda la verdad de aquella comunidad, pero eso me permiti\u00f3 seguir con este proyecto solo abrazando la contradicci\u00f3n y ver que es la \u00fanica manera de contar estas aberraciones que acontecieron en Chile. Esa fue mi gu\u00eda\u00bb.<br \/>\n\u201cDi\u00e1logos en Movimiento\u201d\u00a0fue articulado por diversas entidades gubernamentales como el\u00a0<strong>Ministerio de Educaci\u00f3n<\/strong>\u00a0 y el\u00a0<strong>Consejo Nacional de la Cultura y las Artes<\/strong>\u00a0en el marco del <strong>Plan Nacional de la Lectura (2015-2020)<\/strong>, y que promueve, en distintos \u00e1mbitos de acci\u00f3n, el encuentro entre j\u00f3venes y escritores nacionales e internacionales y sus obras.<br \/>\n<div class=\"et_pb_slider et_pb_slider_fullwidth_off et_pb_gallery_post_type\">\n\t\t\t\t<div class=\"et_pb_slides\">\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En esta oprtunidad se convers\u00f3 en torno al Libro \u00abSprinters. Los ni\u00f1os de Colonia Dignidad\u00bb de la escritora Lola Larra.<\/p>\n","protected":false},"author":2,"featured_media":101912,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[18,8],"tags":[],"class_list":["post-101905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estudiantes","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/posts\/101905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/comments?post=101905"}],"version-history":[{"count":0,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/posts\/101905\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/media?parent=101905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/categories?post=101905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/tags?post=101905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}