{"id":101454,"date":"2017-06-12T07:55:21","date_gmt":"2017-06-12T11:55:21","guid":{"rendered":"http:\/\/www.upla.cl\/noticias\/?p=101454"},"modified":"2018-09-07T18:34:51","modified_gmt":"2018-09-07T21:34:51","slug":"se-acerca-primera-editaton-upla-inacap","status":"publish","type":"post","link":"https:\/\/www.upla.cl\/desarrolloestudiantil\/2017\/06\/12\/se-acerca-primera-editaton-upla-inacap\/","title":{"rendered":"Se acerca primera Editat\u00f3n UPLA-INACAP"},"content":{"rendered":"<p><a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/06\/CREAL_upla.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-101458\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/06\/CREAL_upla-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a>La <strong>Universidad de Playa Ancha<\/strong>, <strong>Inacap sede Maip\u00fa<\/strong> y <strong>Wikimedia Chile<\/strong> se unieron para realizar una editat\u00f3n de traducci\u00f3n enfocada al <strong>Turismo Sustentable<\/strong>, en el marco del llamado de la Organizaci\u00f3n de las Naciones Unidas (ONU), a poner \u00e9nfasis este a\u00f1o en dicho tema.<br \/>\nLa actividad tendr\u00e1 un car\u00e1cter inter-institucional, dado que l Traducci\u00f3n Ingl\u00e9s-Espa\u00f1ol se realizar\u00e1 simult\u00e1neamente con la carrera de <strong>Traducci\u00f3n Ingl\u00e9s-Espa\u00f1ol<\/strong> <strong>de Inacap sede Maip\u00fa<\/strong>, mediante el apoyo y coordinaci\u00f3n del acad\u00e9mico Sergio P\u00e9rez.<br \/>\nLa Editat\u00f3n apunta al desarrollo del inter\u00e9s en los estudiantes por el trabajo colaborativo, a motivar el gusto por la traducci\u00f3n y edici\u00f3n de textos, as\u00ed como apoyar las actividades de extensi\u00f3n de la carrera de Traducci\u00f3n e Interpretaci\u00f3n Ingl\u00e9s-Espa\u00f1ol de esta casa de estudios.<br \/>\n<a href=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/06\/18664477_824095781082286_5552738333328698884_n.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-101457\" src=\"http:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2017\/06\/18664477_824095781082286_5552738333328698884_n-300x300.png\" alt=\"\" width=\"300\" height=\"300\" \/><\/a>Se trata de una edici\u00f3n colectiva y simult\u00e1nea, abierta al p\u00fablico, en la que personas con distintos niveles de experiencia se re\u00fanen presencial o virtualmente \u2014o combinando ambas opciones\u2014 para mejorar o crear art\u00edculos. Dichos documentos son propuestos con antelaci\u00f3n y se enmarcan en una tem\u00e1tica espec\u00edfica, en este caso en el turismo sustentable, utilizando para ello fuentes previamente recopiladas, que en el caso presencial son facilitadas por alguna instituci\u00f3n colaboradora, en este caso, Wikipedia Chile.<br \/>\nEl evento se efectuar\u00e1 el <strong>viernes 16 de junio<\/strong>, a partir de las <strong>12:00 horas<\/strong> en el <strong>Aula Dr. F\u00e9lix Morales Pettorino<\/strong>, para luego continuar desde las 14.00 horas en el Centro de Recursos de Aprendizaje Ense\u00f1anza de Lenguas (CREAL) de la Facultad de Humanidades, hasta las 17:00 horas.<br \/>\nLa invitaci\u00f3n se extiende a toda la comunidad universitaria.<\/p>\n<h5><strong>Programa<\/strong><\/h5>\n<p>12:00 Bienvenida<br \/>\n12:05 Inducci\u00f3n del equipo de Wikimedia Chile (charla en ingl\u00e9s) + preguntas<br \/>\n13:00 Explicaci\u00f3n de la modalidad de los equipos de trabajo<br \/>\n13:15 Receso &#8211;\u00a0Caf\u00e9<br \/>\n14:00 Comienzo Editat\u00f3n de traducci\u00f3n<br \/>\n14:05 Coordinaci\u00f3n por equipos<br \/>\n14:15 Traducci\u00f3n y edici\u00f3n de entradas (1ra ronda)<br \/>\n15:15 Resumen de trabajo<br \/>\n15:30 Receso<br \/>\n15:45 Traducci\u00f3n y edici\u00f3n de entradas (2da ronda \u2013 Revisi\u00f3n y finalizaci\u00f3n)<br \/>\n16:15 Resumen y presentaci\u00f3n de casos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Edici\u00f3n colectiva y simult\u00e1nea de art\u00edculos se realizar\u00e1 el viernes 16 de junio en Aula Dr. F\u00e9lix Morales Pettorino,  desde las 12:00 horas.<\/p>\n","protected":false},"author":2,"featured_media":101458,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[18,8],"tags":[],"class_list":["post-101454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estudiantes","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/posts\/101454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/comments?post=101454"}],"version-history":[{"count":0,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/posts\/101454\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/media?parent=101454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/categories?post=101454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upla.cl\/desarrolloestudiantil\/wp-json\/wp\/v2\/tags?post=101454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}